{"id":255,"count":2,"description":"","link":"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/","name":"usabilidad","slug":"usabilidad","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>usabilidad archivos &#8211; Blog Docente - David P\u00e9rez Alonso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"usabilidad archivos &#8211; Blog Docente - David P\u00e9rez Alonso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Docente - David P\u00e9rez Alonso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DavidPerezProfe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/tag\\\/usabilidad\\\/\",\"url\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/tag\\\/usabilidad\\\/\",\"name\":\"usabilidad archivos &#8211; Blog Docente - David P\u00e9rez Alonso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/tag\\\/usabilidad\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/tag\\\/usabilidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"usabilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/\",\"name\":\"Blog Docente - David P\u00e9rez Alonso\",\"description\":\"Blog sobre mis clases y docencia en Formaci\u00f3n Profesional, Bachillerato y ESO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/davidperezalonso.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"usabilidad archivos &#8211; Blog Docente - David P\u00e9rez Alonso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/","og_locale":"es_ES","og_type":"article","og_title":"usabilidad archivos &#8211; Blog Docente - David P\u00e9rez Alonso","og_url":"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/","og_site_name":"Blog Docente - David P\u00e9rez Alonso","twitter_card":"summary_large_image","twitter_site":"@DavidPerezProfe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/","url":"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/","name":"usabilidad archivos &#8211; Blog Docente - David P\u00e9rez Alonso","isPartOf":{"@id":"https:\/\/davidperezalonso.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/davidperezalonso.com\/blog\/tag\/usabilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/davidperezalonso.com\/blog\/"},{"@type":"ListItem","position":2,"name":"usabilidad"}]},{"@type":"WebSite","@id":"https:\/\/davidperezalonso.com\/blog\/#website","url":"https:\/\/davidperezalonso.com\/blog\/","name":"Blog Docente - David P\u00e9rez Alonso","description":"Blog sobre mis clases y docencia en Formaci\u00f3n Profesional, Bachillerato y ESO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/davidperezalonso.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/davidperezalonso.com\/blog\/wp-json\/wp\/v2\/tags\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/davidperezalonso.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/davidperezalonso.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/davidperezalonso.com\/blog\/wp-json\/wp\/v2\/posts?tags=255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}